{"id":8426,"date":"2025-05-26T18:16:05","date_gmt":"2025-05-26T23:16:05","guid":{"rendered":"https:\/\/florencia.edu.co\/portal\/v4\/?p=8426"},"modified":"2025-06-04T11:59:37","modified_gmt":"2025-06-04T16:59:37","slug":"en-el-marco-del-convenio-interinstitucional-para-el-desarrollo-de-las-practicas-profesionales-universitarias-se-presentaron-los-resultados-de-esta-vigencia-potenciando-e-impactando-a-3-776-estudia","status":"publish","type":"post","link":"https:\/\/florencia.edu.co\/portal\/v4\/en-el-marco-del-convenio-interinstitucional-para-el-desarrollo-de-las-practicas-profesionales-universitarias-se-presentaron-los-resultados-de-esta-vigencia-potenciando-e-impactando-a-3-776-estudia\/","title":{"rendered":"En el marco del convenio interinstitucional para el desarrollo de las PR\u00c1CTICAS PROFESIONALES UNIVERSITARIAS con la UNAD,  se presentaron los resultados  de esta vigencia, potenciando e impactando a 3.776 estudiantes desde la b\u00e1sica primaria hasta la educaci\u00f3n media."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Desarrollo de las Pr\u00e1cticas Profesionales, Pr\u00e1cticas Formativas y Experiencias Profesionales dirigidas a los estudiantes del sector oficial\u00bb<\/h2>\n\n\n\n<p>Dando alcance al convenio de apoyo interinstitucional para el desarrollo de pr\u00e1cticas profesionales universitarias celebrado entre la Alcald\u00eda de Florencia y la Universidad Nacional Abierta y a Distancia UNAD, donde su objeto es: \u201cEstablecer mecanismos de cooperaci\u00f3n interinstitucional entre la Universidad y la Alcald\u00eda de Florencia, con el fin de permitir el desarrollo de las Pr\u00e1cticas Profesionales, Pr\u00e1cticas Profesionales, Pr\u00e1cticas Formativas y Experiencias Profesionales Dirigidas a los estudiantes del sector oficial\u00bb con el fin de permitir el desarrollo de las Pr\u00e1cticas Formativas dirigidas a los estudiantes del sector oficial.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:37.06924%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-4-1024x761.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-4-1024x761.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-4-1024x761.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-4-1024x761.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-4-1024x761.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-4-1024x761.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1902\" data-id=\"8430\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8430\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-4-1024x761.jpeg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-4-1024x761.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 1 of 5 in full-screen\" \/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-4-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-4-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-4-1024x768.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-4-1024x768.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-4-1024x768.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-4-1024x768.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"8431\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8431\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-4-1024x768.jpeg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-4-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 2 of 5 in full-screen\" \/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/18-2-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/18-2-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/18-2-1024x768.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/18-2-1024x768.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/18-2-1024x768.jpeg?strip=info&#038;w=1800&#038;ssl=1 1800w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/18-2-1024x768.jpeg?strip=info&#038;w=2000&#038;ssl=1 2000w\" alt=\"\" data-height=\"1920\" data-id=\"8432\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8432\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/18-2-1024x768.jpeg\" data-width=\"2560\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/18-2-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 3 of 5 in full-screen\" \/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:62.93076%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/22-2-769x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/22-2-769x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/22-2-769x1024.jpeg?strip=info&#038;w=1170&#038;ssl=1 1170w\" alt=\"\" data-height=\"1558\" data-id=\"8433\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8433\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/22-2-769x1024.jpeg\" data-width=\"1170\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/22-2-769x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 4 of 5 in full-screen\" \/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:100.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/23-2-777x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/23-2-777x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/23-2-777x1024.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w\" alt=\"\" data-height=\"1581\" data-id=\"8434\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8434\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/23-2-777x1024.jpeg\" data-width=\"1200\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/23-2-777x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 5 of 5 in full-screen\" \/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n\n<p>Hoy conocimos los resultados, en el marco de la articulaci\u00f3n con los 9 Establecimientos Educativos focalizados para este semestre, logrando potenciar acciones de prevenci\u00f3n, promoci\u00f3n, acompa\u00f1amiento y orientaci\u00f3n, desde las necesidades propias de las estudiantes y estudiantes de las Instituciones Educativas, sumando acciones pedag\u00f3gicas que permiten fortalecer las diferentes problem\u00e1ticas: Presencia de conductas impulsivas o desbordes emocionales, baja tolerancia a la frustraci\u00f3n ante situaciones adversas, Prevenci\u00f3n de Abuso Sexual, Bullyng, Deserci\u00f3n Escolar, Convivencia Escolar entre otras. Acciones de prevenci\u00f3n, promoci\u00f3n, acompa\u00f1amiento y orientaci\u00f3n, desde las necesidades propias de las estudiantes, generando acciones pedag\u00f3gicas para contrarrestar la presencia de conductas impulsivas, la baja tolerancia y la frustraci\u00f3n ante situaciones adversas, prevenci\u00f3n de abuso sexual, bullyng, entre otras.<\/p>\n\n\n\n<p><strong>Instituciones Focalizadas &#8211; semestre I-2025<\/strong><\/p>\n\n\n\n<p>Instituci\u00f3n Educativa Jorge Eliecer Gait\u00e1n<br>Instituci\u00f3n Educativa Antonio Ricaurte<br>Instituci\u00f3n Educativa Agroecol\u00f3gico Amaz\u00f3nico Buinaima<br>Instituci\u00f3n Educativa Barrios Unidos del Sur<br>Instituci\u00f3n Educativa Normal Superior<br>Instituci\u00f3n Educativa Los Pinos<br>Instituci\u00f3n Educativa Los corazones<br>Instituci\u00f3n Educativa La esperanza<br>Instituci\u00f3n Educativa San Francisco<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Desarrollo de las Pr\u00e1cticas Profesionales, Pr\u00e1cticas Formativas y Experiencias Profesionales dirigidas a los estudiantes del sector oficial\u00bb Dando alcance al convenio de apoyo interinstitucional para el desarrollo de pr\u00e1cticas profesionales universitarias celebrado entre la Alcald\u00eda de Florencia y la Universidad Nacional Abierta y a Distancia UNAD, donde su objeto es: \u201cEstablecer mecanismos de cooperaci\u00f3n interinstitucional [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":8429,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-8426","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calidad-educativa"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/24-2-scaled.jpeg?fit=2560%2C1920&ssl=1","jetpack-related-posts":[{"id":4422,"url":"https:\/\/florencia.edu.co\/portal\/v4\/con-viva-la-escuela-mineducacion-busca-reducir-los-rezagos-de-aprendizaje-agudizados-por-la-pandemia\/","url_meta":{"origin":8426,"position":0},"title":"Con \u2018Viva la Escuela\u2019, Mineducaci\u00f3n busca reducir los rezagos de aprendizaje agudizados por la pandemia","author":"Mabiyiceth","date":"13 febrero, 2023","format":false,"excerpt":"En este primer semestre se espera vincular al programa, en calidad de voluntarios, a 5.000 estudiantes de universidades p\u00fablicas y privadas y Escuelas Normales Superiores. Los j\u00f3venes seleccionados por las universidades o normales donde estudian apoyar\u00e1n procesos pedag\u00f3gicos de los docentes del sector oficial en 128 municipios del pa\u00eds, en\u2026","rel":"","context":"En \u00abCobertura Educativa\u00bb","block_context":{"text":"Cobertura Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/cobertura-educativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12026_con-viva-la-escuela-mineducacion-busca-reducir-los-rezagos_1024x600.jpg?fit=1200%2C416&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12026_con-viva-la-escuela-mineducacion-busca-reducir-los-rezagos_1024x600.jpg?fit=1200%2C416&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12026_con-viva-la-escuela-mineducacion-busca-reducir-los-rezagos_1024x600.jpg?fit=1200%2C416&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12026_con-viva-la-escuela-mineducacion-busca-reducir-los-rezagos_1024x600.jpg?fit=1200%2C416&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12026_con-viva-la-escuela-mineducacion-busca-reducir-los-rezagos_1024x600.jpg?fit=1200%2C416&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7035,"url":"https:\/\/florencia.edu.co\/portal\/v4\/en-acompanamiento-de-la-secretaria-de-educacion-de-florencia-estudiantes-en-la-modalidad-agroindustria-alimentaria-de-la-institucion-educativa-jorge-eliecer-gaitan-visitaron-las-instalaciones-de-la-a\/","url_meta":{"origin":8426,"position":1},"title":"En acompa\u00f1amiento de la Secretar\u00eda de Educaci\u00f3n de Florencia, estudiantes en la Modalidad Agroindustria alimentaria de la Instituci\u00f3n Educativa Jorge Eliecer Gait\u00e1n visitaron las instalaciones de la Alcald\u00eda de Florencia, para ofertar sus productos.","author":"SANDRA MILENA SALAZAR RAM\u00d3N","date":"9 septiembre, 2024","format":false,"excerpt":"Visita exitosa de los estudiantes del grado 10.2 y 11.2 de la Instituci\u00f3n Educativa Jorge Eliecer Gait\u00e1n de la Especialidad. Agroindustria. Con el saludo del Secretario de Educaci\u00f3n, y su equipo de trabajo, se inici\u00f3 recorrido de los estudiantes por las instalaciones de la Alcald\u00eda para ofertar sus emprendimientos de\u2026","rel":"","context":"En \u00abCalidad Educativa\u00bb","block_context":{"text":"Calidad Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/calidad-educativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-1.jpeg?fit=1200%2C653&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-1.jpeg?fit=1200%2C653&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-1.jpeg?fit=1200%2C653&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-1.jpeg?fit=1200%2C653&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-1.jpeg?fit=1200%2C653&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6934,"url":"https:\/\/florencia.edu.co\/portal\/v4\/la-alcaldia-municipal-de-florencia-a-traves-de-la-secretaria-de-educacion-invita-a-todos-los-colegios-de-la-ciudad-a-participar-en-el-foro-educativo-2024-somos-amazonia-transformamos-desde\/","url_meta":{"origin":8426,"position":2},"title":"La Alcald\u00eda Municipal de Florencia, a trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n, invita a todos los colegios de la ciudad a participar en el Foro Educativo 2024 \u201cSomos Amazon\u00eda, transformamos desde la Educaci\u00f3n\u201d","author":"SANDRA MILENA SALAZAR RAM\u00d3N","date":"21 agosto, 2024","format":false,"excerpt":"Este evento busca reconocer y valorar las innovadoras pr\u00e1cticas pedag\u00f3gicas que se est\u00e1n llevando a cabo en las aulas de clase. Los docentes de todos los niveles educativos (preescolar, b\u00e1sica y media) tienen la oportunidad de compartir sus experiencias significativas y aprender de las estrategias de sus colegios. \u00bfC\u00f3mo participar?\u2026","rel":"","context":"En \u00abResoluciones\u00bb","block_context":{"text":"Resoluciones","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/resoluciones\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/3-4.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/3-4.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/3-4.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/3-4.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/3-4.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":6207,"url":"https:\/\/florencia.edu.co\/portal\/v4\/vuelve-la-escuela-pae-por-el-fortalecimiento-del-programa-de-alimentacion-escolar-en-los-territorios\/","url_meta":{"origin":8426,"position":3},"title":"Vuelve la Escuela PAE por el fortalecimiento del Programa de Alimentaci\u00f3n Escolar en los territorios","author":"Mabiyiceth","date":"10 noviembre, 2023","format":false,"excerpt":"La Unidad Alimentos para Aprender (UApA) y el SENA se unen para desarrollar procesos de capacitaci\u00f3n a los diferentes actores institucionales y comunitarios del Programa de Alimentaci\u00f3n Escolar (PAE). La meta de la Escuela PAE es fortalecer en el territorio el Programa de Alimentaci\u00f3n Escolar, capacitando a m\u00e1s de 10\u2026","rel":"","context":"En \u00abPrograma de Alimentaci\u00f3n Escolar (PAE)\u00bb","block_context":{"text":"Programa de Alimentaci\u00f3n Escolar (PAE)","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/programa-de-alimentacion-escolar-pae\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17580_vuelve-la-escuela-pae-por-el-fortalecimiento-del-programa_1024x600.jpg?fit=898%2C600&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17580_vuelve-la-escuela-pae-por-el-fortalecimiento-del-programa_1024x600.jpg?fit=898%2C600&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17580_vuelve-la-escuela-pae-por-el-fortalecimiento-del-programa_1024x600.jpg?fit=898%2C600&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17580_vuelve-la-escuela-pae-por-el-fortalecimiento-del-programa_1024x600.jpg?fit=898%2C600&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":6829,"url":"https:\/\/florencia.edu.co\/portal\/v4\/secretaria-de-educacion-municipal-adelanto-taller-de-formacion-en-convivencia-escolar-a-educadores-con-delegada-del-ministerio-de-educacion-nacional\/","url_meta":{"origin":8426,"position":4},"title":"Secretar\u00eda de Educaci\u00f3n Municipal, adelant\u00f3 taller de formaci\u00f3n en Convivencia Escolar a Educadores, con delegada del Ministerio De Educaci\u00f3n Nacional.","author":"Miller","date":"25 junio, 2024","format":false,"excerpt":"Importante jornada de formaci\u00f3n, que cont\u00f3 con la participaci\u00f3n de 98 participantes entre directivos docentes y orientadores escolares de los establecimientos educativos oficiales y no oficiales del municipio de Florencia, el taller de formaci\u00f3n en convivencia, permitir\u00e1 continuar construyendo tejido social en cada uno de los establecimientos educativos, fortaleciendo el\u2026","rel":"","context":"En \u00abEventos\u00bb","block_context":{"text":"Eventos","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/eventos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1-2.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1-2.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1-2.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1-2.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1-2.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4536,"url":"https:\/\/florencia.edu.co\/portal\/v4\/con-exito-se-llevo-a-cabo-la-1-a-mesa-publica-municipal-del-pae-2023\/","url_meta":{"origin":8426,"position":5},"title":"Con \u00e9xito se llev\u00f3 a cabo la 1ra Mesa P\u00fablica Municipal del PAE 2023.","author":"Mabiyiceth","date":"17 abril, 2023","format":false,"excerpt":"La Secretar\u00eda de Educaci\u00f3n de Florencia realiz\u00f3 el pasado 13 de abril la 1ra Mesa P\u00fablica Municipal del Programa de Alimentaci\u00f3n Escolar PAE , en el auditorio de la Universidad Nacional y Distancia UNAD .A la mesa asistieron padres de familia, entidades de control, concejales, estudiantes, delegados del operador del\u2026","rel":"","context":"En \u00abPrograma de Alimentaci\u00f3n Escolar (PAE)\u00bb","block_context":{"text":"Programa de Alimentaci\u00f3n Escolar (PAE)","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/programa-de-alimentacion-escolar-pae\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1ra-MESA-PUBLICA-MUNICIPAL-PAE-ETC-FLORENCIA-18.jpeg?resize=350%2C200&ssl=1","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1ra-MESA-PUBLICA-MUNICIPAL-PAE-ETC-FLORENCIA-18.jpeg?resize=350%2C200&ssl=1 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1ra-MESA-PUBLICA-MUNICIPAL-PAE-ETC-FLORENCIA-18.jpeg?resize=525%2C300&ssl=1 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1ra-MESA-PUBLICA-MUNICIPAL-PAE-ETC-FLORENCIA-18.jpeg?resize=700%2C400&ssl=1 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/1ra-MESA-PUBLICA-MUNICIPAL-PAE-ETC-FLORENCIA-18.jpeg?resize=1050%2C600&ssl=1 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/8426","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/comments?post=8426"}],"version-history":[{"count":5,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/8426\/revisions"}],"predecessor-version":[{"id":8439,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/8426\/revisions\/8439"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/media\/8429"}],"wp:attachment":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/media?parent=8426"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/categories?post=8426"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/tags?post=8426"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}