{"id":8323,"date":"2025-05-10T12:37:33","date_gmt":"2025-05-10T17:37:33","guid":{"rendered":"https:\/\/florencia.edu.co\/portal\/v4\/?p=8323"},"modified":"2025-06-04T11:07:43","modified_gmt":"2025-06-04T16:07:43","slug":"avanzamos-como-actores-involucrados-en-pro-de-lograr-promover-la-ruta-de-desercion-escolar-a-traves-del-mecanismo-de-identificacion-que-nos-permitan-minimizar-los-riesgos-de-desercion-y-problematicas","status":"publish","type":"post","link":"https:\/\/florencia.edu.co\/portal\/v4\/avanzamos-como-actores-involucrados-en-pro-de-lograr-promover-la-ruta-de-desercion-escolar-a-traves-del-mecanismo-de-identificacion-que-nos-permitan-minimizar-los-riesgos-de-desercion-y-problematicas\/","title":{"rendered":"Avanzamos como actores involucrados en pro de lograr promover la ruta de DESERCION ESCOLAR a trav\u00e9s del mecanismo de identificaci\u00f3n que nos permitan minimizar los riesgos de deserci\u00f3n y problem\u00e1ticas como trabajo infantil, alta permanencia en calle y vida en Calle."},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Continuaremos brindando atenci\u00f3n a sus familias para prevenir dichas problem\u00e1ticas.<\/h2>\n\n\n\n<p>Para esta vigencia, se da inicio a los acuerdos de coordinaci\u00f3n y articulaci\u00f3n de la \u201cRuta de Deserci\u00f3n Escolar\u201d&nbsp; donde los actores, en conjunto, buscan potenciar las brechas que presenta actualmente nuestro municipio en temas de deserci\u00f3n escolar, las Instituciones Educativas Oficiales focalizadas para la vigencia son: Instituci\u00f3n Educativa San Francisco de As\u00eds, Instituci\u00f3n Educativa Divino Ni\u00f1o y Ia Instituci\u00f3n Educativa Ciudadela Siglo XXI.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/13-3.jpeg?resize=1024%2C768&#038;ssl=1\" alt=\"\" class=\"wp-image-8327\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/13-3.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/13-3.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/13-3.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/13-3.jpeg?resize=500%2C375&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/13-3.jpeg?resize=800%2C600&amp;ssl=1 800w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/13-3.jpeg?w=1280&amp;ssl=1 1280w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>La Implementaci\u00f3n de \u00abRUTA DE DESERCI\u00d3N ESCOLAR\u00bb contin\u00faa en &nbsp;articulaci\u00f3n con los agentes del Sistema Nacional de Bienestar Familiar: Instituto Colombiano de Bienestar Familiar, Polic\u00eda de Infancia y Adolescencia, Secretar\u00eda de Gobierno, Secretar\u00eda de Inclusi\u00f3n y Reconciliaci\u00f3n Social, Secretar\u00eda de Salud, Secretar\u00eda de Cultura, Deporte y recreaci\u00f3n, Secretar\u00eda de Educaci\u00f3n Municipal, se da inicio a los acuerdos de coordinaci\u00f3n y articulaci\u00f3n en donde los actores en conjunto buscan potenciar las brechas que presenta actualmente nuestro municipio en temas de deserci\u00f3n escolar.<\/p>\n\n\n\n<div class=\"wp-block-jetpack-tiled-gallery aligncenter is-style-rectangular\"><div class=\"\"><div class=\"tiled-gallery__gallery\"><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:62.97322%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/30-2-768x1024.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/30-2-768x1024.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/30-2-768x1024.jpeg?strip=info&#038;w=960&#038;ssl=1 960w\" alt=\"\" data-height=\"1280\" data-id=\"8330\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8330\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/30-2-768x1024.jpeg\" data-width=\"960\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/30-2-768x1024.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 1 of 6 in full-screen\" \/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:37.02678%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/16-2-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/16-2-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/16-2-1024x768.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/16-2-1024x768.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/16-2-1024x768.jpeg?strip=info&#038;w=1600&#038;ssl=1 1600w\" alt=\"\" data-height=\"1200\" data-id=\"8331\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8331\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/16-2-1024x768.jpeg\" data-width=\"1600\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/16-2-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 2 of 6 in full-screen\" \/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-2-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-2-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-2-1024x768.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-2-1024x768.jpeg?strip=info&#038;w=1280&#038;ssl=1 1280w\" alt=\"\" data-height=\"960\" data-id=\"8332\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8332\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-2-1024x768.jpeg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/17-2-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 3 of 6 in full-screen\" \/><\/figure><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/31-2-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/31-2-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/31-2-1024x768.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/31-2-1024x768.jpeg?strip=info&#038;w=1500&#038;ssl=1 1500w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/31-2-1024x768.jpeg?strip=info&#038;w=1600&#038;ssl=1 1600w\" alt=\"\" data-height=\"1200\" data-id=\"8333\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8333\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/31-2-1024x768.jpeg\" data-width=\"1600\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/31-2-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 4 of 6 in full-screen\" \/><\/figure><\/div><\/div><div class=\"tiled-gallery__row\"><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-2-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-2-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-2-1024x768.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-2-1024x768.jpeg?strip=info&#038;w=1280&#038;ssl=1 1280w\" alt=\"\" data-height=\"960\" data-id=\"8334\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8334\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-2-1024x768.jpeg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-2-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 5 of 6 in full-screen\" \/><\/figure><\/div><div class=\"tiled-gallery__col\" style=\"flex-basis:50.00000%\"><figure class=\"tiled-gallery__item\"><img decoding=\"async\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-4-1024x768.jpeg?strip=info&#038;w=600&#038;ssl=1 600w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-4-1024x768.jpeg?strip=info&#038;w=900&#038;ssl=1 900w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-4-1024x768.jpeg?strip=info&#038;w=1200&#038;ssl=1 1200w,https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-4-1024x768.jpeg?strip=info&#038;w=1280&#038;ssl=1 1280w\" alt=\"\" data-height=\"960\" data-id=\"8335\" data-link=\"https:\/\/florencia.edu.co\/portal\/v4\/?attachment_id=8335\" data-url=\"https:\/\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-4-1024x768.jpeg\" data-width=\"1280\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-4-1024x768.jpeg?ssl=1\" data-amp-layout=\"responsive\" role=\"button\" aria-label=\"Open image 6 of 6 in full-screen\" \/><\/figure><\/div><\/div><\/div><\/div><\/div>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Continuaremos brindando atenci\u00f3n a sus familias para prevenir dichas problem\u00e1ticas. Para esta vigencia, se da inicio a los acuerdos de coordinaci\u00f3n y articulaci\u00f3n de la \u201cRuta de Deserci\u00f3n Escolar\u201d&nbsp; donde los actores, en conjunto, buscan potenciar las brechas que presenta actualmente nuestro municipio en temas de deserci\u00f3n escolar, las Instituciones Educativas Oficiales focalizadas para la [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":8324,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[20],"tags":[],"class_list":["post-8323","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cobertura-educativa"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/19-1.jpeg?fit=1280%2C960&ssl=1","jetpack-related-posts":[{"id":8426,"url":"https:\/\/florencia.edu.co\/portal\/v4\/en-el-marco-del-convenio-interinstitucional-para-el-desarrollo-de-las-practicas-profesionales-universitarias-se-presentaron-los-resultados-de-esta-vigencia-potenciando-e-impactando-a-3-776-estudia\/","url_meta":{"origin":8323,"position":0},"title":"En el marco del convenio interinstitucional para el desarrollo de las PR\u00c1CTICAS PROFESIONALES UNIVERSITARIAS con la UNAD,  se presentaron los resultados  de esta vigencia, potenciando e impactando a 3.776 estudiantes desde la b\u00e1sica primaria hasta la educaci\u00f3n media.","author":"SANDRA MILENA SALAZAR RAM\u00d3N","date":"26 mayo, 2025","format":false,"excerpt":"Desarrollo de las Pr\u00e1cticas Profesionales, Pr\u00e1cticas Formativas y Experiencias Profesionales dirigidas a los estudiantes del sector oficial\" Dando alcance al convenio de apoyo interinstitucional para el desarrollo de pr\u00e1cticas profesionales universitarias celebrado entre la Alcald\u00eda de Florencia y la Universidad Nacional Abierta y a Distancia UNAD, donde su objeto es:\u2026","rel":"","context":"En \u00abCalidad Educativa\u00bb","block_context":{"text":"Calidad Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/calidad-educativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/24-2-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/24-2-scaled.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/24-2-scaled.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/24-2-scaled.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/24-2-scaled.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4370,"url":"https:\/\/florencia.edu.co\/portal\/v4\/utiles-desercion\/","url_meta":{"origin":8323,"position":1},"title":"+ \u00datiles -Deserci\u00f3n","author":"Mabiyiceth","date":"19 enero, 2023","format":false,"excerpt":"","rel":"","context":"En \u00abCobertura Educativa\u00bb","block_context":{"text":"Cobertura Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/cobertura-educativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/WhatsApp-Image-2023-01-22-at-6.02.54-PM.jpeg?fit=828%2C756&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/WhatsApp-Image-2023-01-22-at-6.02.54-PM.jpeg?fit=828%2C756&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/WhatsApp-Image-2023-01-22-at-6.02.54-PM.jpeg?fit=828%2C756&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/WhatsApp-Image-2023-01-22-at-6.02.54-PM.jpeg?fit=828%2C756&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2969,"url":"https:\/\/florencia.edu.co\/portal\/v4\/el-20-de-enero-dia-de-la-tercera-gran-donaton-mas-utiles-escolares-menos-desercion\/","url_meta":{"origin":8323,"position":2},"title":"EL 20 DE ENERO, D\u00cdA DE LA TERCERA GRAN DONAT\u00d3N \u201cM\u00c1S \u00daTILES ESCOLARES MENOS DESERCI\u00d3N\u201d.","author":"Miller","date":"13 enero, 2022","format":false,"excerpt":"VID-20220113-WA0064Descargar Convencida del principio que \u201ccon m\u00e1s \u00fatiles escolares se tendr\u00e1 menos deserci\u00f3n escolar\u201d, la gestora social del municipio de Florencia, Yineth Artunduaga Ortiz, program\u00f3 para el 20 de enero del 2022, la TERCERA GRAN DONAT\u00d3N de \u00fatiles escolares, con el fin de favorecer a los ni\u00f1os, ni\u00f1as y adolescentes\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220113-WA0041.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220113-WA0041.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220113-WA0041.jpg?resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220113-WA0041.jpg?resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220113-WA0041.jpg?resize=1050%2C600 3x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220113-WA0041.jpg?resize=1400%2C800 4x"},"classes":[]},{"id":8050,"url":"https:\/\/florencia.edu.co\/portal\/v4\/la-secretaria-de-educacion-adelanta-acciones-pedagogicas-en-la-institucion-educativa-divino-nino-con-el-proposito-de-participar-del-encuentro-nacional-de-estudiantes-para-la-formacion-integral\/","url_meta":{"origin":8323,"position":3},"title":"La Secretar\u00eda de Educaci\u00f3n adelanta acciones pedag\u00f3gicas en la Instituci\u00f3n Educativa Divino Ni\u00f1o, con el prop\u00f3sito de participar del Encuentro Nacional de Estudiantes para la Formaci\u00f3n Integral.","author":"SANDRA MILENA SALAZAR RAM\u00d3N","date":"3 abril, 2025","format":false,"excerpt":"Con el prop\u00f3sito de participar del Encuentro Nacional de Estudiantes para la Formaci\u00f3n Integral, a realizarse en la ciudad de Bogot\u00e1 el pr\u00f3ximo 08 de abril, la Secretar\u00eda de Educaci\u00f3n adelanta acciones pedag\u00f3gicas en la Instituci\u00f3n Educativa Divino Ni\u00f1o, con el fin de reconocer las voces de las ni\u00f1as, ni\u00f1os,\u2026","rel":"","context":"En \u00abCalidad Educativa\u00bb","block_context":{"text":"Calidad Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/calidad-educativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41-1.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41-1.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41-1.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41-1.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41-1.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":8360,"url":"https:\/\/florencia.edu.co\/portal\/v4\/con-mas-de-10-mil-millones-de-pesos-la-alcaldia-de-florencia-a-traves-de-la-secretaria-de-educacion-gestiono-mediante-obras-por-impuesto-la-mejora-del-mobiliario-de-las-instituciones-educativas-in\/","url_meta":{"origin":8323,"position":4},"title":"Con m\u00e1s de $10 mil millones de pesos la Alcald\u00eda de Florencia a trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n, gestion\u00f3 mediante OBRAS POR IMPUESTO, la mejora del mobiliario de las Instituciones Educativas, invirtiendo recursos importantes para dignificar los espacios donde aprenden los ni\u00f1os, ni\u00f1as y j\u00f3venes.","author":"SANDRA MILENA SALAZAR RAM\u00d3N","date":"17 mayo, 2025","format":false,"excerpt":"\u00a1Una educaci\u00f3n de calidad empieza en un aula bien dotada! La administraci\u00f3n municipal de Florencia, bajo el liderazgo del alcalde Marlon Monsalve y a trav\u00e9s de la Secretar\u00eda de Educaci\u00f3n, gestion\u00f3 la financiaci\u00f3n de dos proyectos clave mediante el mecanismo de Obras por Impuestos, orientados a renovar el mobiliario escolar\u2026","rel":"","context":"En \u00abCalidad Educativa\u00bb","block_context":{"text":"Calidad Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/calidad-educativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/25-1.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/25-1.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/25-1.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/25-1.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/25-1.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":4397,"url":"https:\/\/florencia.edu.co\/portal\/v4\/mineducacion-recuerda-la-importancia-de-registrar-los-estudiantes-en-el-sistema-integrado-de-matriculas-simat\/","url_meta":{"origin":8323,"position":5},"title":"Mineducaci\u00f3n recuerda la importancia de registrar los estudiantes en el Sistema Integrado de Matriculas &#8211; SIMAT","author":"Mabiyiceth","date":"7 febrero, 2023","format":false,"excerpt":"El Ministerio de Educaci\u00f3n Nacional hace un llamado para que los rectores de los colegios del pa\u00eds reporten los ni\u00f1os, ni\u00f1as y j\u00f3venes en el Sistema Integrado de Matr\u00edculas \u2013 SIMAT, con el fin de tener organizado y controlado el proceso de matr\u00edcula de todos los estudiantes vinculados al sistema\u2026","rel":"","context":"En \u00abCobertura Educativa\u00bb","block_context":{"text":"Cobertura Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/cobertura-educativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/11999_mineducacion-recuerda-la-importancia-de-registrar-los_1024x600.jpg?fit=740%2C444&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/11999_mineducacion-recuerda-la-importancia-de-registrar-los_1024x600.jpg?fit=740%2C444&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/11999_mineducacion-recuerda-la-importancia-de-registrar-los_1024x600.jpg?fit=740%2C444&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/11999_mineducacion-recuerda-la-importancia-de-registrar-los_1024x600.jpg?fit=740%2C444&ssl=1&resize=700%2C400 2x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/8323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/comments?post=8323"}],"version-history":[{"count":3,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/8323\/revisions"}],"predecessor-version":[{"id":8336,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/8323\/revisions\/8336"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/media\/8324"}],"wp:attachment":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/media?parent=8323"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/categories?post=8323"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/tags?post=8323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}