{"id":7220,"date":"2024-11-06T11:13:18","date_gmt":"2024-11-06T16:13:18","guid":{"rendered":"https:\/\/florencia.edu.co\/portal\/v4\/?p=7220"},"modified":"2024-11-13T09:46:29","modified_gmt":"2024-11-13T14:46:29","slug":"feliz-dia-maestros","status":"publish","type":"post","link":"https:\/\/florencia.edu.co\/portal\/v4\/feliz-dia-maestros\/","title":{"rendered":"\u00a1Feliz d\u00eda Maestros!"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>En el marco de la conmemoraci\u00f3n del d\u00eda del Maestro, compartimos un espacio de reflexi\u00f3n y reconocimiento a su loable labor de educar.<\/p>\n\n\n\n<p>Exaltamos su profesionalismo en los procesos de ense\u00f1anza y aprendizaje. Evento que logr\u00f3 reunir a m\u00e1s de 1000 docentes donde recibieron reconocimiento por su saber inspirador y dedicaci\u00f3n con sus alumnos, un espacio de interacci\u00f3n, reflexi\u00f3n y motivaci\u00f3n, record\u00e1ndoles que su dedicaci\u00f3n, empat\u00eda y amor son pilares fundamentales para educar y formar ni\u00f1os felices. Gracias Maestros!<\/p>\n\n\n\n<div class=\"wp-block-jetpack-slideshow aligncenter\" data-effect=\"slide\"><div class=\"wp-block-jetpack-slideshow_container swiper-container\"><ul class=\"wp-block-jetpack-slideshow_swiper-wrapper swiper-wrapper\"><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"847\" height=\"898\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7224\" data-id=\"7224\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/42.jpg?resize=847%2C898&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/42.jpg?w=847&amp;ssl=1 847w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/42.jpg?resize=283%2C300&amp;ssl=1 283w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/42.jpg?resize=768%2C814&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/42.jpg?resize=500%2C530&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/42.jpg?resize=800%2C848&amp;ssl=1 800w\" sizes=\"(max-width: 847px) 100vw, 847px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7225\" data-id=\"7225\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/44.jpg?resize=1280%2C960&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/44.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/44.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/44.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/44.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/44.jpg?resize=500%2C375&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/44.jpg?resize=800%2C600&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1141\" height=\"946\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7226\" data-id=\"7226\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/51.jpg?resize=1141%2C946&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/51.jpg?w=1141&amp;ssl=1 1141w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/51.jpg?resize=300%2C249&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/51.jpg?resize=1024%2C849&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/51.jpg?resize=768%2C637&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/51.jpg?resize=500%2C415&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/51.jpg?resize=800%2C663&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7227\" data-id=\"7227\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/46-1.jpg?resize=1280%2C960&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/46-1.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/46-1.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/46-1.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/46-1.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/46-1.jpg?resize=500%2C375&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/46-1.jpg?resize=800%2C600&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1133\" height=\"885\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7228\" data-id=\"7228\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/43.jpg?resize=1133%2C885&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/43.jpg?w=1133&amp;ssl=1 1133w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/43.jpg?resize=300%2C234&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/43.jpg?resize=1024%2C800&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/43.jpg?resize=768%2C600&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/43.jpg?resize=500%2C391&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/43.jpg?resize=800%2C625&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"1600\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7229\" data-id=\"7229\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/56.jpg?resize=1200%2C1600&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/56.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/56.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/56.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/56.jpg?resize=1152%2C1536&amp;ssl=1 1152w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/56.jpg?resize=500%2C667&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/56.jpg?resize=800%2C1067&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"1280\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7230\" data-id=\"7230\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/48.jpg?resize=960%2C1280&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/48.jpg?w=960&amp;ssl=1 960w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/48.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/48.jpg?resize=768%2C1024&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/48.jpg?resize=500%2C667&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/48.jpg?resize=800%2C1067&amp;ssl=1 800w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"753\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7231\" data-id=\"7231\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?resize=1600%2C753&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?resize=300%2C141&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?resize=1024%2C482&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?resize=768%2C361&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?resize=1536%2C723&amp;ssl=1 1536w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?resize=500%2C235&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?resize=800%2C377&amp;ssl=1 800w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/55.jpg?resize=1280%2C602&amp;ssl=1 1280w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7232\" data-id=\"7232\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41.jpg?resize=1280%2C960&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41.jpg?resize=500%2C375&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/41.jpg?resize=800%2C600&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7234\" data-id=\"7234\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/68.jpg?resize=1280%2C960&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/68.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/68.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/68.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/68.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/68.jpg?resize=500%2C375&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/68.jpg?resize=800%2C600&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1081\" height=\"959\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7235\" data-id=\"7235\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/69.jpg?resize=1081%2C959&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/69.jpg?w=1081&amp;ssl=1 1081w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/69.jpg?resize=300%2C266&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/69.jpg?resize=1024%2C908&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/69.jpg?resize=768%2C681&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/69.jpg?resize=500%2C444&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/69.jpg?resize=800%2C710&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><li class=\"wp-block-jetpack-slideshow_slide swiper-slide\"><figure><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"960\" alt=\"\" class=\"wp-block-jetpack-slideshow_image wp-image-7236\" data-id=\"7236\" src=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/70.jpg?resize=1280%2C960&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/70.jpg?w=1280&amp;ssl=1 1280w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/70.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/70.jpg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/70.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/70.jpg?resize=500%2C375&amp;ssl=1 500w, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/70.jpg?resize=800%2C600&amp;ssl=1 800w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/li><\/ul><a class=\"wp-block-jetpack-slideshow_button-prev swiper-button-prev swiper-button-white\" role=\"button\"><\/a><a class=\"wp-block-jetpack-slideshow_button-next swiper-button-next swiper-button-white\" role=\"button\"><\/a><a aria-label=\"Pause Slideshow\" class=\"wp-block-jetpack-slideshow_button-pause\" role=\"button\"><\/a><div class=\"wp-block-jetpack-slideshow_pagination swiper-pagination swiper-pagination-white\"><\/div><\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">La Secretar\u00eda de Educaci\u00f3n conmemor\u00f3 su loable labor de educar,  m\u00e1s de 1000 docentes, participaron de este acto de celebraci\u00f3n y reconocimiento. <\/h2>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la conmemoraci\u00f3n del d\u00eda del Maestro, compartimos un espacio de reflexi\u00f3n y reconocimiento a su loable labor de educar. Exaltamos su profesionalismo en los procesos de ense\u00f1anza y aprendizaje. Evento que logr\u00f3 reunir a m\u00e1s de 1000 docentes donde recibieron reconocimiento por su saber inspirador y dedicaci\u00f3n con sus alumnos, un [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":7222,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"jetpack_seo_schema_type":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_vp_format_video_url":"","_vp_image_focal_point":[],"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-7220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-eventos"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/49.jpg?fit=960%2C1280&ssl=1","jetpack-related-posts":[{"id":7394,"url":"https:\/\/florencia.edu.co\/portal\/v4\/la-institucion-educativa-los-pinos-alcanzo-importante-reconocimiento\/","url_meta":{"origin":7220,"position":0},"title":"LA INSTITUCI\u00d3N EDUCATIVA LOS PINOS ALCANZO IMPORTANTE RECONOCIMIENTO","author":"Miller","date":"4 febrero, 2025","format":false,"excerpt":"Gracias al esfuerzo del equipo de docentes de las diferentes \u00e1reas y los directivos de la Instituci\u00f3n Educativa Los Pinos, en desarrollo de la estrategia ANFORA PINISTA.La Instituci\u00f3n Educativa logr\u00f3 significativo reconocimiento en la p\u00e1gina de contacto maestro, este reconocimiento es el resultado de la dedicaci\u00f3n y trabajo en equipo.\u2026","rel":"","context":"En \u00abCalidad Educativa\u00bb","block_context":{"text":"Calidad Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/calidad-educativa\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":6803,"url":"https:\/\/florencia.edu.co\/portal\/v4\/justamente-los-ninos-ninas-y-adolescentes-son-protagonistas-de-la-paz-que-estamos-construyendo\/","url_meta":{"origin":7220,"position":1},"title":"Justamente \u00a1Los ni\u00f1os, ni\u00f1as y adolescentes son protagonistas de la paz que estamos construyendo!","author":"Miller","date":"20 junio, 2024","format":false,"excerpt":"Gracias al trabajo articulado que realiza la Secretar\u00eda de Educaci\u00f3n Municipal de Florencia con el Programa Nacional de Educaci\u00f3n para la Paz EDUCAPAZ, y el Programa de la Jurisdicci\u00f3n Especial para la Paz (JEP) se logr\u00f3 que nuestro territorio fuera seleccionado para que los directivos-as docentes, docentes y orientadores-as de\u2026","rel":"","context":"En \u00abSin categor\u00eda\u00bb","block_context":{"text":"Sin categor\u00eda","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/sin-categoria\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/2-1.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/2-1.jpeg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/2-1.jpeg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/2-1.jpeg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/2-1.jpeg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":3476,"url":"https:\/\/florencia.edu.co\/portal\/v4\/feliz-dia-maestrs\/","url_meta":{"origin":7220,"position":2},"title":"FElIZ D\u00cdA MAESTR@S!","author":"Mabiyiceth","date":"15 mayo, 2022","format":false,"excerpt":"Es tan grande la profesi\u00f3n que desempe\u00f1an cada d\u00eda, que no encuentro palabras que abarquen todo el significado que tiene la labor de ser profesor, docente, maestro. Solo agradezco a cada uno de ustedes mis maestros, mis colegas por el aporte constante a la sociedad en medio de las adversidades\u2026","rel":"","context":"En \u00abAdministrativa\u00bb","block_context":{"text":"Administrativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/administrativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220515-WA0015.jpg?fit=848%2C1200&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220515-WA0015.jpg?fit=848%2C1200&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220515-WA0015.jpg?fit=848%2C1200&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/IMG-20220515-WA0015.jpg?fit=848%2C1200&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":2929,"url":"https:\/\/florencia.edu.co\/portal\/v4\/el-retorno-a-la-presencialidad-de-los-ninos-ninas-adolescentes-y-jovenes-es-una-prioridad-del-gobierno-y-una-garantia-para-el-derecho-a-la-educacion\/","url_meta":{"origin":7220,"position":3},"title":"El retorno a la presencialidad de los ni\u00f1os, ni\u00f1as, adolescentes y j\u00f3venes es una prioridad del Gobierno y una garant\u00eda para el derecho a la educaci\u00f3n","author":"Mabiyiceth","date":"7 enero, 2022","format":false,"excerpt":"Actualizado: 06 de enero de 2022 El retorno presencial con bioseguridad es fundamental para avanzar en el aprendizaje y desarrollo integral de los ni\u00f1os, ni\u00f1as y j\u00f3venes. El Gobierno Nacional le cumple a los docentes y directivos y les brinda mejoras importantes en sus condiciones laborales. Bogot\u00e1 D.C., 6 de\u2026","rel":"","context":"En \u00abCobertura Educativa\u00bb","block_context":{"text":"Cobertura Educativa","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/cobertura-educativa\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/articles-408682_recurso_1.jpg?fit=740%2C422&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/articles-408682_recurso_1.jpg?fit=740%2C422&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/articles-408682_recurso_1.jpg?fit=740%2C422&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/articles-408682_recurso_1.jpg?fit=740%2C422&ssl=1&resize=700%2C400 2x"},"classes":[]},{"id":8748,"url":"https:\/\/florencia.edu.co\/portal\/v4\/con-la-participacion-de-12-instituciones-educativas-realizamos-el-4-encuentro-de-proyectos-ambientales-de-educacion-inicial-prae-nivel-preescolar\/","url_meta":{"origin":7220,"position":4},"title":"Con la participaci\u00f3n de 12 Instituciones Educativas, realizamos el 4\u00b0 Encuentro de Proyectos Ambientales de Educaci\u00f3n Inicial PRAE -Nivel PREESCOLAR.","author":"SANDRA MILENA SALAZAR RAM\u00d3N","date":"8 septiembre, 2025","format":false,"excerpt":"Al reunir a los peque\u00f1os en un espacio donde puedan interactuar, explorar y aprender juntos, se promueve un ambiente enriquecedor que estimula su curiosidad natural y su deseo de aprender y compartir sus saberes estrechando el v\u00ednculo entre la familia y la escuela puesto que se hace necesario el acompa\u00f1amiento\u2026","rel":"","context":"En \u00abEventos\u00bb","block_context":{"text":"Eventos","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/eventos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-7.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-7.jpeg?fit=1200%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-7.jpeg?fit=1200%2C800&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-7.jpeg?fit=1200%2C800&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/12-7.jpeg?fit=1200%2C800&ssl=1&resize=1050%2C600 3x"},"classes":[]},{"id":7149,"url":"https:\/\/florencia.edu.co\/portal\/v4\/la-secretaria-de-educacion-realizo-con-exito-el-foro-educativo-2024-somos-amazonia-transformamos-desde-la-educacion-16-establecimientos-educativos-rurales-y-urbanos-presentaron-sus-experiencias\/","url_meta":{"origin":7220,"position":5},"title":"La Secretar\u00eda de Educaci\u00f3n realiz\u00f3 con \u00e9xito el Foro Educativo 2024  \u00abSomos Amazonia, transformamos desde la Educaci\u00f3n\u00bb 16 establecimientos educativos, rurales y urbanos presentaron sus experiencias significativas.","author":"SANDRA MILENA SALAZAR RAM\u00d3N","date":"17 octubre, 2024","format":false,"excerpt":"Las experiencias ganadoras, tendr\u00e1n la oportunidad de representar a Florencia en el Foro Nacional. Ganadora IE Jos\u00e9 Antonio Gal\u00e1n, con la Experiencia \" La Escuela como Escenario para Construir Paz\" Ganadora IE Los Andes, con la experiencia \"Sembrar Convivencia, es Cosechar Paz\" En el marco de la COP16, y con\u2026","rel":"","context":"En \u00abEventos\u00bb","block_context":{"text":"Eventos","link":"https:\/\/florencia.edu.co\/portal\/v4\/category\/eventos\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-1.jpg?fit=1200%2C900&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-1.jpg?fit=1200%2C900&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-1.jpg?fit=1200%2C900&ssl=1&resize=525%2C300 1.5x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-1.jpg?fit=1200%2C900&ssl=1&resize=700%2C400 2x, https:\/\/i0.wp.com\/florencia.edu.co\/portal\/v4\/wp-content\/uploads\/21-1.jpg?fit=1200%2C900&ssl=1&resize=1050%2C600 3x"},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/7220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/comments?post=7220"}],"version-history":[{"count":5,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/7220\/revisions"}],"predecessor-version":[{"id":7238,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/posts\/7220\/revisions\/7238"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/media\/7222"}],"wp:attachment":[{"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/media?parent=7220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/categories?post=7220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/florencia.edu.co\/portal\/v4\/wp-json\/wp\/v2\/tags?post=7220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}